{"id":306,"count":2,"description":"","link":"https:\/\/sifrreports.com\/ar\/tag\/%d8%a7%d9%84%d8%aa%d9%88%d8%aa%d8%b1%d8%a7%d8%aa-%d8%a7%d9%84%d8%b9%d8%b3%d9%83%d8%b1%d9%8a%d8%a9-%d9%81%d9%8a-%d8%a7%d9%84%d8%b4%d8%b1%d9%82-%d8%a7%d9%84%d8%a3%d9%88%d8%b3%d8%b7\/","name":"\u0627\u0644\u062a\u0648\u062a\u0631\u0627\u062a \u0627\u0644\u0639\u0633\u0643\u0631\u064a\u0629 \u0641\u064a \u0627\u0644\u0634\u0631\u0642 \u0627\u0644\u0623\u0648\u0633\u0637","slug":"%d8%a7%d9%84%d8%aa%d9%88%d8%aa%d8%b1%d8%a7%d8%aa-%d8%a7%d9%84%d8%b9%d8%b3%d9%83%d8%b1%d9%8a%d8%a9-%d9%81%d9%8a-%d8%a7%d9%84%d8%b4%d8%b1%d9%82-%d8%a7%d9%84%d8%a3%d9%88%d8%b3%d8%b7","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u0627\u0644\u062a\u0648\u062a\u0631\u0627\u062a \u0627\u0644\u0639\u0633\u0643\u0631\u064a\u0629 \u0641\u064a \u0627\u0644\u0634\u0631\u0642 \u0627\u0644\u0623\u0648\u0633\u0637 - \u0635\u0641\u0631<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sifrreports.com\/ar\/tag\/\u0627\u0644\u062a\u0648\u062a\u0631\u0627\u062a-\u0627\u0644\u0639\u0633\u0643\u0631\u064a\u0629-\u0641\u064a-\u0627\u0644\u0634\u0631\u0642-\u0627\u0644\u0623\u0648\u0633\u0637\/\" \/>\n<meta property=\"og:locale\" content=\"ar_AR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0627\u0644\u062a\u0648\u062a\u0631\u0627\u062a \u0627\u0644\u0639\u0633\u0643\u0631\u064a\u0629 \u0641\u064a \u0627\u0644\u0634\u0631\u0642 \u0627\u0644\u0623\u0648\u0633\u0637 - \u0635\u0641\u0631\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sifrreports.com\/ar\/tag\/\u0627\u0644\u062a\u0648\u062a\u0631\u0627\u062a-\u0627\u0644\u0639\u0633\u0643\u0631\u064a\u0629-\u0641\u064a-\u0627\u0644\u0634\u0631\u0642-\u0627\u0644\u0623\u0648\u0633\u0637\/\" \/>\n<meta property=\"og:site_name\" content=\"\u0635\u0641\u0631\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sifrreports.com\/ar\/wp-content\/uploads\/sites\/7\/2026\/01\/cropped-Sifr-Favicon.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"512\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@sifrreports\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/sifrreports.com\\\/ar\\\/tag\\\/%d8%a7%d9%84%d8%aa%d9%88%d8%aa%d8%b1%d8%a7%d8%aa-%d8%a7%d9%84%d8%b9%d8%b3%d9%83%d8%b1%d9%8a%d8%a9-%d9%81%d9%8a-%d8%a7%d9%84%d8%b4%d8%b1%d9%82-%d8%a7%d9%84%d8%a3%d9%88%d8%b3%d8%b7\\\/\",\"url\":\"https:\\\/\\\/sifrreports.com\\\/ar\\\/tag\\\/%d8%a7%d9%84%d8%aa%d9%88%d8%aa%d8%b1%d8%a7%d8%aa-%d8%a7%d9%84%d8%b9%d8%b3%d9%83%d8%b1%d9%8a%d8%a9-%d9%81%d9%8a-%d8%a7%d9%84%d8%b4%d8%b1%d9%82-%d8%a7%d9%84%d8%a3%d9%88%d8%b3%d8%b7\\\/\",\"name\":\"\u0627\u0644\u062a\u0648\u062a\u0631\u0627\u062a \u0627\u0644\u0639\u0633\u0643\u0631\u064a\u0629 \u0641\u064a \u0627\u0644\u0634\u0631\u0642 \u0627\u0644\u0623\u0648\u0633\u0637 - \u0635\u0641\u0631\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sifrreports.com\\\/ar\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sifrreports.com\\\/ar\\\/tag\\\/%d8%a7%d9%84%d8%aa%d9%88%d8%aa%d8%b1%d8%a7%d8%aa-%d8%a7%d9%84%d8%b9%d8%b3%d9%83%d8%b1%d9%8a%d8%a9-%d9%81%d9%8a-%d8%a7%d9%84%d8%b4%d8%b1%d9%82-%d8%a7%d9%84%d8%a3%d9%88%d8%b3%d8%b7\\\/#breadcrumb\"},\"inLanguage\":\"ar\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sifrreports.com\\\/ar\\\/tag\\\/%d8%a7%d9%84%d8%aa%d9%88%d8%aa%d8%b1%d8%a7%d8%aa-%d8%a7%d9%84%d8%b9%d8%b3%d9%83%d8%b1%d9%8a%d8%a9-%d9%81%d9%8a-%d8%a7%d9%84%d8%b4%d8%b1%d9%82-%d8%a7%d9%84%d8%a3%d9%88%d8%b3%d8%b7\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/sifrreports.com\\\/ar\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0627\u0644\u062a\u0648\u062a\u0631\u0627\u062a \u0627\u0644\u0639\u0633\u0643\u0631\u064a\u0629 \u0641\u064a \u0627\u0644\u0634\u0631\u0642 \u0627\u0644\u0623\u0648\u0633\u0637\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sifrreports.com\\\/ar\\\/#website\",\"url\":\"https:\\\/\\\/sifrreports.com\\\/ar\\\/\",\"name\":\"\u0635\u0641\u0631\",\"description\":\"\u0645\u0646\u0635\u0629 \u0631\u0627\u0635\u062f\u0629 \u062a\u062d\u0644\u064a\u0644\u064a\u0629 \u0644\u0642\u0636\u0627\u064a\u0627 \u062d\u0642\u0648\u0642 \u0627\u0644\u0625\u0646\u0633\u0627\u0646\",\"publisher\":{\"@id\":\"https:\\\/\\\/sifrreports.com\\\/ar\\\/#organization\"},\"alternateName\":\"\u0635\u0641\u0631\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sifrreports.com\\\/ar\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ar\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/sifrreports.com\\\/ar\\\/#organization\",\"name\":\"\u0635\u0641\u0631\",\"alternateName\":\"\u0635\u0641\u0631\",\"url\":\"https:\\\/\\\/sifrreports.com\\\/ar\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ar\",\"@id\":\"https:\\\/\\\/sifrreports.com\\\/ar\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/sifrreports.com\\\/ar\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/logo-for-dark-BG.svg\",\"contentUrl\":\"https:\\\/\\\/sifrreports.com\\\/ar\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/logo-for-dark-BG.svg\",\"width\":688,\"height\":278,\"caption\":\"\u0635\u0641\u0631\"},\"image\":{\"@id\":\"https:\\\/\\\/sifrreports.com\\\/ar\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Sifrreports\",\"https:\\\/\\\/x.com\\\/sifrreports\",\"https:\\\/\\\/www.instagram.com\\\/sifrreports\",\"https:\\\/\\\/www.youtube.com\\\/@sifrreports\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0627\u0644\u062a\u0648\u062a\u0631\u0627\u062a \u0627\u0644\u0639\u0633\u0643\u0631\u064a\u0629 \u0641\u064a \u0627\u0644\u0634\u0631\u0642 \u0627\u0644\u0623\u0648\u0633\u0637 - \u0635\u0641\u0631","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sifrreports.com\/ar\/tag\/\u0627\u0644\u062a\u0648\u062a\u0631\u0627\u062a-\u0627\u0644\u0639\u0633\u0643\u0631\u064a\u0629-\u0641\u064a-\u0627\u0644\u0634\u0631\u0642-\u0627\u0644\u0623\u0648\u0633\u0637\/","og_locale":"ar_AR","og_type":"article","og_title":"\u0627\u0644\u062a\u0648\u062a\u0631\u0627\u062a \u0627\u0644\u0639\u0633\u0643\u0631\u064a\u0629 \u0641\u064a \u0627\u0644\u0634\u0631\u0642 \u0627\u0644\u0623\u0648\u0633\u0637 - \u0635\u0641\u0631","og_url":"https:\/\/sifrreports.com\/ar\/tag\/\u0627\u0644\u062a\u0648\u062a\u0631\u0627\u062a-\u0627\u0644\u0639\u0633\u0643\u0631\u064a\u0629-\u0641\u064a-\u0627\u0644\u0634\u0631\u0642-\u0627\u0644\u0623\u0648\u0633\u0637\/","og_site_name":"\u0635\u0641\u0631","og_image":[{"width":512,"height":512,"url":"https:\/\/sifrreports.com\/ar\/wp-content\/uploads\/sites\/7\/2026\/01\/cropped-Sifr-Favicon.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@sifrreports","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/sifrreports.com\/ar\/tag\/%d8%a7%d9%84%d8%aa%d9%88%d8%aa%d8%b1%d8%a7%d8%aa-%d8%a7%d9%84%d8%b9%d8%b3%d9%83%d8%b1%d9%8a%d8%a9-%d9%81%d9%8a-%d8%a7%d9%84%d8%b4%d8%b1%d9%82-%d8%a7%d9%84%d8%a3%d9%88%d8%b3%d8%b7\/","url":"https:\/\/sifrreports.com\/ar\/tag\/%d8%a7%d9%84%d8%aa%d9%88%d8%aa%d8%b1%d8%a7%d8%aa-%d8%a7%d9%84%d8%b9%d8%b3%d9%83%d8%b1%d9%8a%d8%a9-%d9%81%d9%8a-%d8%a7%d9%84%d8%b4%d8%b1%d9%82-%d8%a7%d9%84%d8%a3%d9%88%d8%b3%d8%b7\/","name":"\u0627\u0644\u062a\u0648\u062a\u0631\u0627\u062a \u0627\u0644\u0639\u0633\u0643\u0631\u064a\u0629 \u0641\u064a \u0627\u0644\u0634\u0631\u0642 \u0627\u0644\u0623\u0648\u0633\u0637 - \u0635\u0641\u0631","isPartOf":{"@id":"https:\/\/sifrreports.com\/ar\/#website"},"breadcrumb":{"@id":"https:\/\/sifrreports.com\/ar\/tag\/%d8%a7%d9%84%d8%aa%d9%88%d8%aa%d8%b1%d8%a7%d8%aa-%d8%a7%d9%84%d8%b9%d8%b3%d9%83%d8%b1%d9%8a%d8%a9-%d9%81%d9%8a-%d8%a7%d9%84%d8%b4%d8%b1%d9%82-%d8%a7%d9%84%d8%a3%d9%88%d8%b3%d8%b7\/#breadcrumb"},"inLanguage":"ar"},{"@type":"BreadcrumbList","@id":"https:\/\/sifrreports.com\/ar\/tag\/%d8%a7%d9%84%d8%aa%d9%88%d8%aa%d8%b1%d8%a7%d8%aa-%d8%a7%d9%84%d8%b9%d8%b3%d9%83%d8%b1%d9%8a%d8%a9-%d9%81%d9%8a-%d8%a7%d9%84%d8%b4%d8%b1%d9%82-%d8%a7%d9%84%d8%a3%d9%88%d8%b3%d8%b7\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/sifrreports.com\/ar\/"},{"@type":"ListItem","position":2,"name":"\u0627\u0644\u062a\u0648\u062a\u0631\u0627\u062a \u0627\u0644\u0639\u0633\u0643\u0631\u064a\u0629 \u0641\u064a \u0627\u0644\u0634\u0631\u0642 \u0627\u0644\u0623\u0648\u0633\u0637"}]},{"@type":"WebSite","@id":"https:\/\/sifrreports.com\/ar\/#website","url":"https:\/\/sifrreports.com\/ar\/","name":"\u0635\u0641\u0631","description":"\u0645\u0646\u0635\u0629 \u0631\u0627\u0635\u062f\u0629 \u062a\u062d\u0644\u064a\u0644\u064a\u0629 \u0644\u0642\u0636\u0627\u064a\u0627 \u062d\u0642\u0648\u0642 \u0627\u0644\u0625\u0646\u0633\u0627\u0646","publisher":{"@id":"https:\/\/sifrreports.com\/ar\/#organization"},"alternateName":"\u0635\u0641\u0631","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sifrreports.com\/ar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ar"},{"@type":"Organization","@id":"https:\/\/sifrreports.com\/ar\/#organization","name":"\u0635\u0641\u0631","alternateName":"\u0635\u0641\u0631","url":"https:\/\/sifrreports.com\/ar\/","logo":{"@type":"ImageObject","inLanguage":"ar","@id":"https:\/\/sifrreports.com\/ar\/#\/schema\/logo\/image\/","url":"https:\/\/sifrreports.com\/ar\/wp-content\/uploads\/sites\/7\/2026\/01\/logo-for-dark-BG.svg","contentUrl":"https:\/\/sifrreports.com\/ar\/wp-content\/uploads\/sites\/7\/2026\/01\/logo-for-dark-BG.svg","width":688,"height":278,"caption":"\u0635\u0641\u0631"},"image":{"@id":"https:\/\/sifrreports.com\/ar\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Sifrreports","https:\/\/x.com\/sifrreports","https:\/\/www.instagram.com\/sifrreports","https:\/\/www.youtube.com\/@sifrreports"]}]}},"_links":{"self":[{"href":"https:\/\/sifrreports.com\/ar\/wp-json\/wp\/v2\/tags\/306","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sifrreports.com\/ar\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/sifrreports.com\/ar\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/sifrreports.com\/ar\/wp-json\/wp\/v2\/posts?tags=306"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}